{"id":1901,"date":"2010-05-05T00:00:00","date_gmt":"2010-05-05T00:00:00","guid":{"rendered":"https:\/\/newsroom.ferrovial.com\/news\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/"},"modified":"2022-12-21T10:35:47","modified_gmt":"2022-12-21T09:35:47","slug":"galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos","status":"publish","type":"new","link":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/","title":{"rendered":"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos."},"content":{"rendered":"    <section class=\"wysiwyg text-editor \" id=\"\">\n        <div class=\"container container--narrow container--p-10\">\n            <p>El consejero de econom\u00eda e industria de la Xunta ha declarado hoy 5 de Mayo, que ya tiene definida una red primaria de infraestructuras de recarga y que contar\u00e1 con medio millar de puntos de recarga repartidos en toda la Comunidad aut\u00f3noma.<\/p>\n<p>Adem\u00e1s el consejero ha manifestado su clara apuesta por el futuro del sector de la automoci\u00f3n que actualmente genera cerca de 4.000 empleados, con unos beneficios de 8.400 millones de euros entre las empresas gallegas. El apoyo al veh\u00edculo el\u00e9ctrico por parte del Gobierno de la Xunta est\u00e1 dentro del Plan global de impulso a la automoci\u00f3n re-M\u00f3vete, dotado con un presupuesto de 120 millones de euros, y estimular\u00e1 desde la fabricaci\u00f3n de los modelos, como industrias auxiliares y comercializaci\u00f3n.<\/p>\n<p>Otra de las medidas estrella que pretende adoptar la Xunta para fomentar el desarrollo de la movilidad sostenible en la regi\u00f3n, es la de subvencionar con hasta 7.000 euros la compra de este tipo de veh\u00edculos, al igual que ya han hecho otras Comunidades. Las previsiones auguran que para 2014 estar\u00e1n en circulaci\u00f3n 10.000 veh\u00edculos.<\/p>\n<p>El plan propuesto, incluye adem\u00e1s un fondo extra de 6 millones, para la comercializaci\u00f3n de veh\u00edculos y compensar de \u00e9sta forma el efecto negativo que provocar\u00e1 la subida del IVA.<\/p>\n<p>El programa apoyar\u00e1 econ\u00f3micamente a la asociaci\u00f3n francesa Peugeot-Citro\u00ebn, fabricantes en Galicia, con fondos entre 35 y 40 millones de euros para el desarrollo de nuevos modelos, con el compromiso por parte de las empresas de mantener la estabilidad y garantizar el empleo a medio plazo.<\/p>\n<p>Fuente:<br \/>\n  <a href=\"http:\/\/www.ecomove-project.eu\/\" title=\"Ecomove\"><u>Ecomove<\/u><\/a><\/p>\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","nivel-2":[936],"nivel-5":[],"nivel-1":[],"nivel-3":[],"nivel-4":[],"class_list":["post-1901","new","type-new","status-publish","hentry","nivel-2-conservacion-del-medio-ambiente"],"acf":[],"yoast_head":"<title>Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias<\/title>\n<meta name=\"description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/\" \/>\n<meta property=\"og:site_name\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ferrovial\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T09:35:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ferrovial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/\",\"name\":\"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias\",\"isPartOf\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\"},\"datePublished\":\"2010-05-05T00:00:00+00:00\",\"dateModified\":\"2022-12-21T09:35:47+00:00\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"breadcrumb\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/newsroom.ferrovial.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"name\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"publisher\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\",\"name\":\"Ferrovial S.A.\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"contentUrl\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"width\":600,\"height\":300,\"caption\":\"Ferrovial S.A.\"},\"image\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ferrovial\",\"https:\/\/x.com\/ferrovial\",\"https:\/\/www.instagram.com\/ferrovial\/\",\"https:\/\/www.linkedin.com\/company\/ferrovial\",\"https:\/\/www.pinterest.es\/ferrovial\/\",\"https:\/\/www.youtube.com\/ferrovial\",\"https:\/\/en.wikipedia.org\/wiki\/Ferrovial\"]}]}<\/script>","yoast_head_json":{"title":"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/","og_locale":"es_ES","og_type":"article","og_title":"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias","og_description":"Sala de prensa Ferrovial | \u00daltimas noticias","og_url":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/","og_site_name":"Sala de prensa Ferrovial | \u00daltimas noticias","article_publisher":"https:\/\/www.facebook.com\/ferrovial","article_modified_time":"2022-12-21T09:35:47+00:00","twitter_card":"summary_large_image","twitter_site":"@ferrovial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/","url":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/","name":"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos. Sala de prensa Ferrovial | \u00daltimas noticias","isPartOf":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#website"},"datePublished":"2010-05-05T00:00:00+00:00","dateModified":"2022-12-21T09:35:47+00:00","description":"Sala de prensa Ferrovial | \u00daltimas noticias","breadcrumb":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/galicia-sera-la-primera-comunidad-que-regulara-las-infraestructuras-de-recarga-de-los-futuros-coches-electricos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/newsroom.ferrovial.com\/es\/"},{"@type":"ListItem","position":2,"name":"Galicia ser\u00e1 la primera Comunidad que regular\u00e1 las infraestructuras de recarga de los futuros coches el\u00e9ctricos."}]},{"@type":"WebSite","@id":"https:\/\/newsroom.ferrovial.com\/es\/#website","url":"https:\/\/newsroom.ferrovial.com\/es\/","name":"Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","publisher":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization","name":"Ferrovial S.A.","url":"https:\/\/newsroom.ferrovial.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","contentUrl":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","width":600,"height":300,"caption":"Ferrovial S.A."},"image":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ferrovial","https:\/\/x.com\/ferrovial","https:\/\/www.instagram.com\/ferrovial\/","https:\/\/www.linkedin.com\/company\/ferrovial","https:\/\/www.pinterest.es\/ferrovial\/","https:\/\/www.youtube.com\/ferrovial","https:\/\/en.wikipedia.org\/wiki\/Ferrovial"]}]}},"_links":{"self":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/1901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/types\/new"}],"replies":[{"embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/comments?post=1901"}],"version-history":[{"count":1,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/1901\/revisions"}],"predecessor-version":[{"id":118083,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/1901\/revisions\/118083"}],"wp:attachment":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/media?parent=1901"}],"wp:term":[{"taxonomy":"nivel-2","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-2?post=1901"},{"taxonomy":"nivel-5","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-5?post=1901"},{"taxonomy":"nivel-1","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-1?post=1901"},{"taxonomy":"nivel-3","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-3?post=1901"},{"taxonomy":"nivel-4","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-4?post=1901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}