{"id":2889,"date":"2007-10-18T00:00:00","date_gmt":"2007-10-18T00:00:00","guid":{"rendered":"https:\/\/newsroom.ferrovial.com\/news\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/"},"modified":"2022-12-21T11:16:16","modified_gmt":"2022-12-21T10:16:16","slug":"la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue","status":"publish","type":"new","link":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/","title":{"rendered":"La AEMA recomienda fijar objetivos \u00abclaros y realistas\u00bb para lograr un Medio Ambiente \u00absaludable\u00bb en la UE"},"content":{"rendered":"    <section class=\"wysiwyg text-editor \" id=\"\">\n        <div class=\"container container--narrow container--p-10\">\n            <p>(<a href=\"http:\/\/www.eleconomista.es\/\" target=\"_blank\">eleconomista.es<\/a>).- La Agencia Europea de Medio Ambiente (AEMA) ha hecho p\u00fablico el Informe &#8216;El Medio Ambiente en Europa: cuarta evaluaci\u00f3n&#8217; en el que recomienda a los ministros de la UE aunar fuerzas para conseguir un Medio Ambiente \u00absaludable\u00bb en la regi\u00f3n, por lo que solicita \u00abmejorar la aplicaci\u00f3n de las pol\u00edticas existentes y establecer unos objetivos claros y realistas\u00bb.<\/p>\n<p>El documento tambi\u00e9n recomienda poner en marcha un sistema compartido de informaci\u00f3n medioambiental para \u00abcompensar la actual escasez de informaci\u00f3n fidedigna, accesible y comparable sobre el Medio Ambiente en toda la regi\u00f3n\u00bb.<\/p>\n<p>Este Informe fue presentado en Belgrado (Serbia) con motivo de la sesi\u00f3n inaugural de la VI Conferencia ministerial &#8216;Medio Ambiente para Europa\u00bb, organizada por la Comisi\u00f3n Econ\u00f3mica de las Naciones Unidas para Europa (CEPE-ONU) y es el \u00faltimo de una serie que la AEMA ha publicado durante los \u00faltimos 15 a\u00f1os. Todos aquellos interesados, pueden consultarlo en la p\u00e1gina web &#8216;www.eea.europa.eu\/pan-european\/fourth-assessment&#8217;.<\/p>\n<p>El texto eval\u00faa los progresos de 53 pa\u00edses &#8211;que conforman un espacio cuya poblaci\u00f3n total supera los 870 millones de habitantes&#8211; en materia de Medio Ambiente y se\u00f1ala que la agricultura, el turismo, el transporte y la energ\u00eda son los principales causantes de los problemas medioambientales. Adem\u00e1s, las actuales pautas de consumo y producci\u00f3n imponen \u00abuna mayor demanda de recursos naturales, lo que incrementa los riesgos\u00bb, reza el Informe.<\/p>\n<p>Todos estos factores repercuten sobre la calidad del agua, el aire y el suelo. As\u00ed, por ejemplo, m\u00e1s de 100 millones de personas no tienen acceso a agua potable mientras que en muchos pa\u00edses de Europa Oriental, el C\u00e1ucaso, Asia Central y Europa Sudoriental, la calidad del suministro de agua y saneamiento se ha deteriorado durante los \u00faltimos 15 a\u00f1os, lo que afecta especialmente a la poblaci\u00f3n de las zonas rurales.<\/p>\n<p>Respecto a la contaminaci\u00f3n atmosf\u00e9rica, los niveles actuales acortan en medio a\u00f1o la esperanza de vida en los pa\u00edses europeos y suponen \u00abuna amenaza para un desarrollo infantil saludable\u00bb.<\/p>\n<p>El Informe tambi\u00e9n constata una p\u00e9rdida de la biodiversidad, lo que se refleja en que m\u00e1s de 700 especies europeas se encuentran en peligro de extinci\u00f3n como resultado de la destrucci\u00f3n, degradaci\u00f3n y alteraci\u00f3n de sus h\u00e1bitats.<\/p>\n<p>La AEMA &#8211;www.eea.europa.eu&#8211; tiene su sede en Copenhague (Dinamarca) y trabaja a favor de una mejora significativa del Medio Ambiente europeo por lo que proporciona una informaci\u00f3n actualizada y fidedigna a los responsables de la pol\u00edtica medioambiental y al p\u00fablico en general.<\/p>\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","nivel-2":[],"nivel-5":[],"nivel-1":[],"nivel-3":[],"nivel-4":[],"class_list":["post-2889","new","type-new","status-publish","hentry"],"acf":[],"yoast_head":"<title>La AEMA recomienda fijar objetivos &quot;claros y realistas&quot; para lograr un Medio Ambiente &quot;saludable&quot; en la UE Sala de prensa Ferrovial | \u00daltimas noticias<\/title>\n<meta name=\"description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La AEMA recomienda fijar objetivos &quot;claros y realistas&quot; para lograr un Medio Ambiente &quot;saludable&quot; en la UE Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ferrovial\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T10:16:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ferrovial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/\",\"name\":\"La AEMA recomienda fijar objetivos \\\"claros y realistas\\\" para lograr un Medio Ambiente \\\"saludable\\\" en la UE Sala de prensa Ferrovial | \u00daltimas noticias\",\"isPartOf\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\"},\"datePublished\":\"2007-10-18T00:00:00+00:00\",\"dateModified\":\"2022-12-21T10:16:16+00:00\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"breadcrumb\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/newsroom.ferrovial.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La AEMA recomienda fijar objetivos \u00abclaros y realistas\u00bb para lograr un Medio Ambiente \u00absaludable\u00bb en la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"name\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"publisher\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\",\"name\":\"Ferrovial S.A.\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"contentUrl\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"width\":600,\"height\":300,\"caption\":\"Ferrovial S.A.\"},\"image\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ferrovial\",\"https:\/\/x.com\/ferrovial\",\"https:\/\/www.instagram.com\/ferrovial\/\",\"https:\/\/www.linkedin.com\/company\/ferrovial\",\"https:\/\/www.pinterest.es\/ferrovial\/\",\"https:\/\/www.youtube.com\/ferrovial\",\"https:\/\/en.wikipedia.org\/wiki\/Ferrovial\"]}]}<\/script>","yoast_head_json":{"title":"La AEMA recomienda fijar objetivos \"claros y realistas\" para lograr un Medio Ambiente \"saludable\" en la UE Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/","og_locale":"es_ES","og_type":"article","og_title":"La AEMA recomienda fijar objetivos \"claros y realistas\" para lograr un Medio Ambiente \"saludable\" en la UE Sala de prensa Ferrovial | \u00daltimas noticias","og_description":"Sala de prensa Ferrovial | \u00daltimas noticias","og_url":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/","og_site_name":"Sala de prensa Ferrovial | \u00daltimas noticias","article_publisher":"https:\/\/www.facebook.com\/ferrovial","article_modified_time":"2022-12-21T10:16:16+00:00","twitter_card":"summary_large_image","twitter_site":"@ferrovial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/","url":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/","name":"La AEMA recomienda fijar objetivos \"claros y realistas\" para lograr un Medio Ambiente \"saludable\" en la UE Sala de prensa Ferrovial | \u00daltimas noticias","isPartOf":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#website"},"datePublished":"2007-10-18T00:00:00+00:00","dateModified":"2022-12-21T10:16:16+00:00","description":"Sala de prensa Ferrovial | \u00daltimas noticias","breadcrumb":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsroom.ferrovial.com\/es\/noticias\/la-aema-recomienda-fijar-objetivos-claros-y-realistas-para-lograr-un-medio-ambiente-saludable-en-la-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/newsroom.ferrovial.com\/es\/"},{"@type":"ListItem","position":2,"name":"La AEMA recomienda fijar objetivos \u00abclaros y realistas\u00bb para lograr un Medio Ambiente \u00absaludable\u00bb en la UE"}]},{"@type":"WebSite","@id":"https:\/\/newsroom.ferrovial.com\/es\/#website","url":"https:\/\/newsroom.ferrovial.com\/es\/","name":"Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","publisher":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization","name":"Ferrovial S.A.","url":"https:\/\/newsroom.ferrovial.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","contentUrl":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","width":600,"height":300,"caption":"Ferrovial S.A."},"image":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ferrovial","https:\/\/x.com\/ferrovial","https:\/\/www.instagram.com\/ferrovial\/","https:\/\/www.linkedin.com\/company\/ferrovial","https:\/\/www.pinterest.es\/ferrovial\/","https:\/\/www.youtube.com\/ferrovial","https:\/\/en.wikipedia.org\/wiki\/Ferrovial"]}]}},"_links":{"self":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/2889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/types\/new"}],"replies":[{"embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/comments?post=2889"}],"version-history":[{"count":1,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/2889\/revisions"}],"predecessor-version":[{"id":118934,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/new\/2889\/revisions\/118934"}],"wp:attachment":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/media?parent=2889"}],"wp:term":[{"taxonomy":"nivel-2","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-2?post=2889"},{"taxonomy":"nivel-5","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-5?post=2889"},{"taxonomy":"nivel-1","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-1?post=2889"},{"taxonomy":"nivel-3","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-3?post=2889"},{"taxonomy":"nivel-4","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-4?post=2889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}