{"id":252,"date":"2002-09-03T00:00:00","date_gmt":"2002-09-03T00:00:00","guid":{"rendered":"https:\/\/newsroom.ferrovial.com\/press_releases\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/"},"modified":"2022-12-21T12:28:25","modified_gmt":"2022-12-21T11:28:25","slug":"ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability","status":"publish","type":"press_release","link":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/","title":{"rendered":"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability"},"content":{"rendered":"    <section class=\"wysiwyg text-editor \" id=\"\">\n        <div class=\"container container--narrow container--p-10\">\n            <p><strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"logotipo Ferrovial\" src=\"https:\/\/www.ferrovial.com\/wp-content\/uploads\/2007\/05\/img_112350429106_2242005135916.gif\" alt=\"logotipo Ferrovial\" width=\"200\" height=\"86\" \/><\/strong>Estos indicadores constituyen el principal referente en el mundo de compa\u00f1\u00edas comprometidas en su actuaci\u00f3n con los criterios de sostenibilidad<\/strong><\/p>\n<p>Madrid, 4 de septiembre de 2002<\/p>\n<p>Ferrovial es el primer grupo constructor espa\u00f1ol seleccionado para formar parte de <a title=\"\u00cdndice Dow Jones Sustainability\" href=\"http:\/\/www.sustainability-indices.com\/\" target=\"_blank\" rel=\"dofollow\"> los \u00edndices Dow Jones Sustainability<\/a>, principal referente a nivel mundial de compa\u00f1\u00edas comprometidas en su actuaci\u00f3n con los criterios de sostenibilidad.<\/p>\n<p>Los \u00edndices, elaborados por Dow Jones, STOXX Limited y SAM Group y revisados anualmente, responden a la demanda de informaci\u00f3n de los mercados internacionales en relaci\u00f3n a la capacidad de las empresas para gestionar a largo plazo sus actividades de forma responsable, de acuerdo a las exigencias econ\u00f3micas, medioambientales y sociales.<\/p>\n<p><strong>Dimensi\u00f3n econ\u00f3mica, medioambiental y social de la empresa <\/strong><\/p>\n<p>La revisi\u00f3n anual, celebrada hoy en Zurich (Suiza), ha incluido un total de 300 compa\u00f1\u00edas de 23 pa\u00edses que desarrollan sus actividades en t\u00e9rminos de sostenibilidad. The Dow Jones STOXX Sustainability Indexes incluye una selecci\u00f3n de las compa\u00f1\u00edas que forman parte del \u00edndice Dow Jones STOXX 600 con las mejores actuaciones en t\u00e9rminos de sostenibilidad. El proceso de selecci\u00f3n se realiza de acuerdo a unos indicadores definidos por Dow Jones Sustainability Indexes y verificados externamente. El resto de compa\u00f1\u00edas espa\u00f1olas incluidas en los \u00edndices son: BBVA, SCH, Telef\u00f3nica, Iberdrola y Endesa e Inditex, que se han incorporado en esta \u00faltima revisi\u00f3n.<\/p>\n<p>Entre los componentes analizados en cada una de las dimensiones se encuentran: <strong>Dimensi\u00f3n Econ\u00f3mica<\/strong> (gobierno corporativo, relaci\u00f3n con inversores, planificaci\u00f3n estrat\u00e9gica, gesti\u00f3n de riesgos, c\u00f3digos de conducta, etc.); <strong>Dimensi\u00f3n Mediambiental<\/strong> (publicaci\u00f3n en Informe Anual,\u00a0 actuaci\u00f3n y gesti\u00f3n medioambiental de las actividades, pol\u00edticas en materia de reciclaje y aprovechamiento energ\u00e9tico, etc.); <strong>Dimensi\u00f3n Social<\/strong>, (indicadores de Capital Humano, gesti\u00f3n de Recursos Humanos, publicaci\u00f3n en Informe Anual, pol\u00edtica de prevenci\u00f3n, as\u00ed como la implicaci\u00f3n en el desarrollo social de las comunidades de nuestro entorno).<\/p>\n<p><strong>Compromiso con el desarrollo sostenible <\/strong><\/p>\n<p>Ferrovial ha fijado entre sus prioridades de gesti\u00f3n el respeto a la sociedad y al medio ambiente. Su Informe Anual 2001 recoge el esquema de triple cuenta de resultados (financieros, medioambientales y sociales) y, en materia medioambiental, ha sido la primera constructora en el mundo en desarrollar e implantar de un Sistema de Gesti\u00f3n Medioambiental y publicar un <a title=\"Ferrovial ISR e \u00cdndices de Sostenibilidad\" href=\"https:\/\/www.ferrovial.com\/es-es\/sostenibilidad\/rsc\/\" target=\"_blank\" rel=\"dofollow\"> Indice de Comportamiento Medioambiental <\/a>(ICM). Ferrovial es miembro del Pacto Mundial de Naciones Unidas, desde abril de 2002, por el que se compromete a promover y respetar los nueve principios universales en el \u00e1mbito de los derechos humanos, las normas laborales y la protecci\u00f3n al medio ambiente.<\/p>\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","nivel-2":[907,936,2215,977,1904,1045],"nivel-5":[],"nivel-1":[],"nivel-3":[],"nivel-4":[],"class_list":["post-252","press_release","type-press_release","status-publish","hentry","nivel-2-accionistas-e-inversores","nivel-2-conservacion-del-medio-ambiente","nivel-2-eficiencia-energetica","nivel-2-gobierno-corporativo","nivel-2-recursos-humanos","nivel-2-sostenibilidad"],"acf":[],"yoast_head":"<title>Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias<\/title>\n<meta name=\"description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:description\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/\" \/>\n<meta property=\"og:site_name\" content=\"Sala de prensa Ferrovial | \u00daltimas noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ferrovial\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T11:28:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ferrovial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/\",\"name\":\"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias\",\"isPartOf\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\"},\"datePublished\":\"2002-09-03T00:00:00+00:00\",\"dateModified\":\"2022-12-21T11:28:25+00:00\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"breadcrumb\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/newsroom.ferrovial.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notas de Prensa\",\"item\":\"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#website\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"name\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"description\":\"Sala de prensa Ferrovial | \u00daltimas noticias\",\"publisher\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#organization\",\"name\":\"Ferrovial S.A.\",\"url\":\"https:\/\/newsroom.ferrovial.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"contentUrl\":\"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg\",\"width\":600,\"height\":300,\"caption\":\"Ferrovial S.A.\"},\"image\":{\"@id\":\"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ferrovial\",\"https:\/\/x.com\/ferrovial\",\"https:\/\/www.instagram.com\/ferrovial\/\",\"https:\/\/www.linkedin.com\/company\/ferrovial\",\"https:\/\/www.pinterest.es\/ferrovial\/\",\"https:\/\/www.youtube.com\/ferrovial\",\"https:\/\/en.wikipedia.org\/wiki\/Ferrovial\"]}]}<\/script>","yoast_head_json":{"title":"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/","og_locale":"es_ES","og_type":"article","og_title":"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias","og_description":"Sala de prensa Ferrovial | \u00daltimas noticias","og_url":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/","og_site_name":"Sala de prensa Ferrovial | \u00daltimas noticias","article_publisher":"https:\/\/www.facebook.com\/ferrovial","article_modified_time":"2022-12-21T11:28:25+00:00","twitter_card":"summary_large_image","twitter_site":"@ferrovial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/","url":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/","name":"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability Sala de prensa Ferrovial | \u00daltimas noticias","isPartOf":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#website"},"datePublished":"2002-09-03T00:00:00+00:00","dateModified":"2022-12-21T11:28:25+00:00","description":"Sala de prensa Ferrovial | \u00daltimas noticias","breadcrumb":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/ferrovial-primer-grupo-constructor-espanol-seleccionado-para-formar-parte-de-los-indices-dow-jones-sustainability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/newsroom.ferrovial.com\/es\/"},{"@type":"ListItem","position":2,"name":"Notas de Prensa","item":"https:\/\/newsroom.ferrovial.com\/es\/notas-prensa\/"},{"@type":"ListItem","position":3,"name":"Ferrovial, primer grupo constructor espa\u00f1ol seleccionado para formar parte de los \u00edndices Dow Jones Sustainability"}]},{"@type":"WebSite","@id":"https:\/\/newsroom.ferrovial.com\/es\/#website","url":"https:\/\/newsroom.ferrovial.com\/es\/","name":"Sala de prensa Ferrovial | \u00daltimas noticias","description":"Sala de prensa Ferrovial | \u00daltimas noticias","publisher":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsroom.ferrovial.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newsroom.ferrovial.com\/es\/#organization","name":"Ferrovial S.A.","url":"https:\/\/newsroom.ferrovial.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","contentUrl":"https:\/\/static.newsroom.ferrovial.com\/wp-content\/uploads\/2018\/07\/15145720\/Ferrovial_Logotipo1.jpg","width":600,"height":300,"caption":"Ferrovial S.A."},"image":{"@id":"https:\/\/newsroom.ferrovial.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ferrovial","https:\/\/x.com\/ferrovial","https:\/\/www.instagram.com\/ferrovial\/","https:\/\/www.linkedin.com\/company\/ferrovial","https:\/\/www.pinterest.es\/ferrovial\/","https:\/\/www.youtube.com\/ferrovial","https:\/\/en.wikipedia.org\/wiki\/Ferrovial"]}]}},"_links":{"self":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/press_release\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/types\/press_release"}],"replies":[{"embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/comments?post=252"}],"version-history":[{"count":1,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/press_release\/252\/revisions"}],"predecessor-version":[{"id":110327,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/press_release\/252\/revisions\/110327"}],"wp:attachment":[{"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/media?parent=252"}],"wp:term":[{"taxonomy":"nivel-2","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-2?post=252"},{"taxonomy":"nivel-5","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-5?post=252"},{"taxonomy":"nivel-1","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-1?post=252"},{"taxonomy":"nivel-3","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-3?post=252"},{"taxonomy":"nivel-4","embeddable":true,"href":"https:\/\/newsroom.ferrovial.com\/es\/wp-json\/wp\/v2\/nivel-4?post=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}